{"id":12404,"date":"2023-06-15T13:48:17","date_gmt":"2023-06-15T10:48:17","guid":{"rendered":"https:\/\/moh.gov.so\/so\/?page_id=12404"},"modified":"2023-06-26T13:57:49","modified_gmt":"2023-06-26T10:57:49","slug":"warbixinadda-2","status":"publish","type":"page","link":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/","title":{"rendered":"WARBIXINADDA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12404\" class=\"elementor elementor-12404\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa44eda elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fa44eda\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcac946\" data-id=\"dcac946\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62168e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62168e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-40298f3\" data-id=\"40298f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8278be elementor-widget__width-auto elementor-widget elementor-widget-ova_heading\" data-id=\"b8278be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"ova_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ova-heading\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<p class=\"sub-title \">WARBIXINADDA<\/p>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d79c1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d79c1e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a7b45f\" data-id=\"4a7b45f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-142902a elementor-widget elementor-widget-ucaddon_posts_search_filter\" data-id=\"142902a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"ucaddon_posts_search_filter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Search Filter -->\n\t\t<link id='font-awesome-css' href='https:\/\/moh.gov.so\/so\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/moh.gov.so\/so\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Search Filter *\/\n\n#uc_posts_search_filter_elementor_142902a-wrapper\n{\n  display:flex;\n}\n\n#uc_posts_search_filter_elementor_142902a\n{\n  width:100%;\n}\n#uc_posts_search_filter_elementor_142902a .uc-search-filter__input\n{\n  width:100%;\n  flex-grow:1;\n}\n\n#uc_posts_search_filter_elementor_142902a .uc-search-filter-btn\n{\n  display:flex;\n  align-items:center;\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_posts_search_filter_elementor_142902a .uc-search-filter-input-wrapper\n{\n  position: relative;\n  display:flex;\n  align-items:center;\n}\n\n\n#uc_posts_search_filter_elementor_142902a .uc-search-filter-btn .ue-btn-icon\n{\n  line-height:1em;\n}\n\n\n\n#uc_posts_search_filter_elementor_142902a .uc-search-filter-btn .ue-btn-icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_posts_search_filter_elementor_142902a ::-webkit-input-placeholder { \/* Edge *\/\n  color: #909090;\n}\n\n#uc_posts_search_filter_elementor_142902a :-ms-input-placeholder { \/* Internet Explorer 10-11 *\/\n  color: #909090;\n}\n\n#uc_posts_search_filter_elementor_142902a ::placeholder {\n  color: #909090;\n}\n\n#uc_posts_search_filter_elementor_142902a .uc-search-filter-indicator{\n\tposition: absolute;\n  \ttop: 50%;\n    transform: translate(0, -50%);\n    height: 100%;\n  \tdisplay: flex;\n    align-items: center;\n    justify-content: center;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc-search-filter-wrapper\" id=\"uc_posts_search_filter_elementor_142902a-wrapper\" >\n  <div id=\"uc_posts_search_filter_elementor_142902a\" class=\"uc-search-filter uc-grid-filter\" data-filtertype=\"search\"> \n\n      \n      <div class=\"uc-search-filter-input-wrapper\">\n\n        <input type=\"text\" class=\"uc-search-filter__input\" placeholder=\"Search...\">\n\n        \n                      <div class=\"uc-search-filter-indicator\"><i class='fas fa-search'><\/i><\/div>\n          \n\n      <\/div>\n\n  <\/div>\n<\/div>\n\t\t\t<!-- end Search Filter -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f41be55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f41be55\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8fd0f6d\" data-id=\"8fd0f6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82cbcff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82cbcff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-747526f\" data-id=\"747526f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f641ef elementor-widget elementor-widget-heading\" data-id=\"8f641ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TYPE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-62f8393\" data-id=\"62f8393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8b23a elementor-widget elementor-widget-heading\" data-id=\"3f8b23a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FILLE NAME\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-52e4d61\" data-id=\"52e4d61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdb88f4 elementor-widget elementor-widget-heading\" data-id=\"cdb88f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DOWNLOADS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-459919b elementor-widget elementor-widget-ucaddon_post_list\" data-id=\"459919b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"ucaddon_post_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Post List -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post List *\/\n\n\r\n@keyframes uc_post_list_elementor_459919b__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_list_elementor_459919b .uc_post_list_box{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_list_elementor_459919b .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_list_elementor_459919b .uc-entrance-animate {\r\n\tanimation: uc_post_list_elementor_459919b__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_list_elementor_459919b\n{\n  display:grid;\n}\n\n\n#uc_post_list_elementor_459919b .uc_post_list_image div\n{\n  background-size:cover;\n  background-position:center;\n}\n\n\n.uc_post_list .uc_post_list_box{\n\tposition: relative;\n\toverflow: hidden;\n\tdisplay: flex;\n}\n\n#uc_post_list_elementor_459919b .uc_post_list_image\n{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_post_list_elementor_459919b .uc_post_list_image img\n{\n  width:100%;\n  display:block;\n  transition:0.3s;\n  \n}\n\n\n.uc_post_list_title a{\n\tcolor: #333333;\n}\n.uc_post_list_date{\n\tfont-size: 12px;\n}\n\n#uc_post_list_elementor_459919b .uc_post_list_content\n{\n  display:flex;\n  flex-direction:column;\n  flex:1;\n}\n\n#uc_post_list_elementor_459919b .uc_more_btn{\n\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_list_elementor_459919b .button-on-side\n{\n  display:flex;\n  align-items:center;\n}\n\n\n.ue-grid-item-category a\n{\n  display:inline-block;\n  font-size:10px;\n  text-transform:uppercase;\n}\n\n#uc_post_list_elementor_459919b .ue-meta-data\n{\n  \n  display:flex;\n\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_list_elementor_459919b .ue-grid-item-meta-data\n{\n      display:inline-flex;\n      align-items:center;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_list_elementor_459919b .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_list_elementor_459919b .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n\n\n#uc_post_list_elementor_459919b .ue-debug-meta\n{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n.uc-remote-parent .uc_post_list_box{\n\tcursor:pointer;\n}\n\n#uc_post_list_elementor_459919b .ue-post-link-overlay\n{\n  display:block;\n  position:absolute;\n  top:0;\n  bottom:0;\n  right:0;\n  left:0;\n}\n\n<\/style>\n\n\t\t\t<div class=\"uc_post_list uc-items-wrapper uc-filterable-grid \" id=\"uc_post_list_elementor_459919b\"  data-ajax='true'  data-filterbehave='mixed'  querydata='{&quot;count_posts&quot;:10,&quot;total_posts&quot;:16,&quot;page&quot;:1,&quot;num_pages&quot;:2,&quot;orderby&quot;:&quot;date&quot;,&quot;orderdir&quot;:&quot;desc&quot;}' >    \t\n  <div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Quarterly-Healtrh-Statistics-Bulletin.-final_signed.pdf JULY \u2013 SEPTEMBER 2023<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2023\/12\/Quarterly-Healtrh-Statistics-Bulletin.-final_signed.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/quarterly-healtrh-statistics-bulletin-final_signed-pdf-july-september-2023\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">SOMALIA HEALTH BULLETIN SEMI ANNUAL REPORT FROM JAN TO JUN 2023<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2023\/12\/LAST-Final-Report-for-SEMI-ANNUAL-HEALTH-STATISTIC_231223_143553.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/last-final-report-for-semi-annual-health-statistic_231223_143553\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">SEMI-ANNUAL HEALTH STATISTICS BULLETIN FOR HMIS JAN-JUN 2023, Report<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2023\/09\/SEMI-ANNUAL-HEALTH-STATISTICS-BULLETIN-FOR-HMIS-JAN-JUN-2023-1.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/semi-annual-health-statistics-bulletin-for-hmis-jan-jun-2023-report\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Health Sector Resource Mapping and Expenditure Tracking Report 2018 \u2013 2020<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2022\/11\/Health-Sector-Resource-Mapping-Expenditure.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/health-sector-resource-mapping-and-expenditure-tracking-report-2018-2020\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">The First Malaria Indicator Survey in Somalia, 2014<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2020\/07\/The-First-Malaria-Indicator-Survey-in-Somalia-2014.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/the-first-malaria-indicator-survey-in-somalia-2014\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Population Estimation Survey 2014 -Somalia<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2020\/07\/Population-Estimation-Survey-2014-Somalia.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/population-estimation-survey-2014-somalia\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">2016_SARA_Somalia_CountryReport_final_draft_30dec2016-<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2020\/07\/2016_SARA_Somalia_CountryReport_final_draft_30dec2016-.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/2016_sara_somalia_countryreport_final_draft_30dec2016\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Somali Service Availability and Readiness Assessment 2016<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2023\/03\/Somali_Country-Report_Draft-4.12.16.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/somali-service-availability-and-readiness-assessment-2016\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Essential Health Services in times of COVID19 Report<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2022\/11\/Essential-Health-Services-in-times-of-COVID19-Report.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/essential-health-services-in-times-of-covid19-report\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\">\n  \n  \t    <div class=\"uc_post_list_image\">\n                    <img decoding=\"async\" src=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                        \n         <div class=\"uc_post_list_title\">Somalia MPR Phase Report FINAL_020914<\/a><\/div>\t\n         \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\"><\/div>        \n                 \n      <\/div>\n    <\/div>\n     \n          <div class=\"button-on-side\">\n           <a href=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/2022\/11\/Somalia-MPR-Phas-Report-FINAL_020914.pdf\" target=\"_self\" href='https:\/\/moh.gov.so\/so\/pdfs\/somalia-mpr-phase-report-final_020914\/' class=\"uc_more_btn  \" title=\"\">Download<\/a>\n     <\/div>\n       \n  \n   <\/div>\n\n<\/div>\n\n\n  <div id=\"uc_post_list_elementor_459919b_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No PDFs found<\/div>\n\n\n\t\t\t<!-- end Post List -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3be8f8 elementor-widget elementor-widget-ucaddon_archive_pagination\" data-id=\"b3be8f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"ucaddon_archive_pagination.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Post Pagination -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post Pagination *\/\n\n#uc_archive_pagination_elementor_b3be8f8 nav\n{\n  padding:0px;\n  margin:0px;\n}\n\n#uc_archive_pagination_elementor_b3be8f8 \n{\n  display:flex;\n  flex-wrap: wrap;\n  justify-content:flex-end;\n}\n\n#uc_archive_pagination_elementor_b3be8f8 .nav-links\n{\n  display:flex;\n  justify-content:flex-end;\n}\n\n#uc_archive_pagination_elementor_b3be8f8 .nav-links > *\n{\n}\n\n#uc_archive_pagination_elementor_b3be8f8 .page-numbers\n{\n  display:flex;\n  \n  align-items:center;\n  justify-content:center;\n  transition:0.3s;\n  line-height:1em;\n}\n\n\n#uc_archive_pagination_elementor_b3be8f8 a.page-numbers, #uc_archive_pagination_elementor_b3be8f8 .dots\n{\n  color:;\n  background-color:;\n}\n\n#uc_archive_pagination_elementor_b3be8f8 a.page-numbers:hover\n{\n  color:;\n  background-color:#eeeeee;\n}\n\n#uc_archive_pagination_elementor_b3be8f8 .page-numbers.current,\n#uc_archive_pagination_elementor_b3be8f8 .page-numbers.current:hover\n{\n  background-color:#000000;\n  color:#ffffff;\n}\n\n\n#uc_archive_pagination_elementor_b3be8f8 .page-numbers.prev, #uc_archive_pagination_elementor_b3be8f8 .page-numbers.next\n{\n  padding-left:15px;\n  padding-right:15px;\n}\n\n\n\n#uc_archive_pagination_elementor_b3be8f8 .prev:before {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f053\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-right:10px;}\n\n#uc_archive_pagination_elementor_b3be8f8 .next:after {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f054\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-left:10px;}\n\n#uc_archive_pagination_elementor_b3be8f8.uc-ajax-loading{\n\topacity:1 !important;\n}\n\n#uc_archive_pagination_elementor_b3be8f8.uc-ajax-loading .current{\n\tposition:relative;\n    overflow:hidden;\n}\n\n\n#uc_archive_pagination_elementor_b3be8f8.uc-ajax-loading .current:before{\n  content: \"\";\n  display:block;\n  width:100%;\n  height:100%;\n  box-sizing:border-box;\n  position:absolute;\n  top:0px;\n  left:0px;\n  background-color: #c2c2c2;\n  animation: uc-spinning-border 0.5s linear infinite;\n  opacity:50%;\n  border-radius:inherit;\n}\n\n@keyframes uc-spinning-border {\n\t0%{transform: scale(0);}\n\t100%{transform: scale(1); }\t\n}\n\n\n\n<\/style>\n\n\t\t\t<div id=\"uc_archive_pagination_elementor_b3be8f8\" class=\"archive_pagination uc-filter-pagination\">\n<span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/moh.gov.so\/so\/warbixinadda-2\/2\/\">2<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/moh.gov.so\/so\/warbixinadda-2\/2\/\">Next<\/a>\n<\/div>\n\t\t\t<!-- end Post Pagination -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WARBIXINADDA TYPE FILLE NAME DOWNLOADS The First Malaria Indicator Survey in Somalia, 2014 Download Population Estimation Survey 2014 -Somalia Download 2016_SARA_Somalia_CountryReport_final_draft_30dec2016- Download Somali Service Availability and Readiness Assessment 2016 Download [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12404","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moh.gov.so\/so\/warbixinadda-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya\" \/>\n<meta property=\"og:description\" content=\"WARBIXINADDA TYPE FILLE NAME DOWNLOADS The First Malaria Indicator Survey in Somalia, 2014 Download Population Estimation Survey 2014 -Somalia Download 2016_SARA_Somalia_CountryReport_final_draft_30dec2016- Download Somali Service Availability and Readiness Assessment 2016 Download [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moh.gov.so\/so\/warbixinadda-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Wasaaradda Caafimaadka Soomaaliya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MoHSomalia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T10:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MoH_Somalia\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/\",\"url\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/\",\"name\":\"WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/wp-content\\\/uploads\\\/ac_assets\\\/uc_post_list\\\/\\\/placeholder.svg\",\"datePublished\":\"2023-06-15T10:48:17+00:00\",\"dateModified\":\"2023-06-26T10:57:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/wp-content\\\/uploads\\\/ac_assets\\\/uc_post_list\\\/\\\/placeholder.svg\",\"contentUrl\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/wp-content\\\/uploads\\\/ac_assets\\\/uc_post_list\\\/\\\/placeholder.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/warbixinadda-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WARBIXINADDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#website\",\"url\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/\",\"name\":\"Wasaaradda Caafimaadka Soomaaliya\",\"description\":\"Wasaaradda Caafimaadka &amp; Daryeelka Bulshadda - Dowladda Federaalka Soomaaliya\",\"publisher\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#organization\",\"name\":\"Ministry Of Health & Human Services- Federal Government Of Somalia (FGS)\",\"url\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moh.gov.so\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/271707230_295945135892800_6969106877740325906_n.jpg\",\"contentUrl\":\"https:\\\/\\\/moh.gov.so\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/271707230_295945135892800_6969106877740325906_n.jpg\",\"width\":515,\"height\":515,\"caption\":\"Ministry Of Health & Human Services- Federal Government Of Somalia (FGS)\"},\"image\":{\"@id\":\"https:\\\/\\\/moh.gov.so\\\/so\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MoHSomalia\",\"https:\\\/\\\/x.com\\\/MoH_Somalia\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MinistryofHealthSomalia\",\"https:\\\/\\\/moh.gov.so\\\/en\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/","og_locale":"en_US","og_type":"article","og_title":"WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya","og_description":"WARBIXINADDA TYPE FILLE NAME DOWNLOADS The First Malaria Indicator Survey in Somalia, 2014 Download Population Estimation Survey 2014 -Somalia Download 2016_SARA_Somalia_CountryReport_final_draft_30dec2016- Download Somali Service Availability and Readiness Assessment 2016 Download [&hellip;]","og_url":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/","og_site_name":"Wasaaradda Caafimaadka Soomaaliya","article_publisher":"https:\/\/www.facebook.com\/MoHSomalia","article_modified_time":"2023-06-26T10:57:49+00:00","og_image":[{"url":"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@MoH_Somalia","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/","url":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/","name":"WARBIXINADDA - Wasaaradda Caafimaadka Soomaaliya","isPartOf":{"@id":"https:\/\/moh.gov.so\/so\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/#primaryimage"},"image":{"@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/#primaryimage"},"thumbnailUrl":"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg","datePublished":"2023-06-15T10:48:17+00:00","dateModified":"2023-06-26T10:57:49+00:00","breadcrumb":{"@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moh.gov.so\/so\/warbixinadda-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/#primaryimage","url":"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg","contentUrl":"https:\/\/moh.gov.so\/so\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/moh.gov.so\/so\/warbixinadda-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/moh.gov.so\/so\/"},{"@type":"ListItem","position":2,"name":"WARBIXINADDA"}]},{"@type":"WebSite","@id":"https:\/\/moh.gov.so\/so\/#website","url":"https:\/\/moh.gov.so\/so\/","name":"Wasaaradda Caafimaadka Soomaaliya","description":"Wasaaradda Caafimaadka &amp; Daryeelka Bulshadda - Dowladda Federaalka Soomaaliya","publisher":{"@id":"https:\/\/moh.gov.so\/so\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moh.gov.so\/so\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/moh.gov.so\/so\/#organization","name":"Ministry Of Health & Human Services- Federal Government Of Somalia (FGS)","url":"https:\/\/moh.gov.so\/so\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/moh.gov.so\/so\/#\/schema\/logo\/image\/","url":"https:\/\/moh.gov.so\/en\/wp-content\/uploads\/2022\/07\/271707230_295945135892800_6969106877740325906_n.jpg","contentUrl":"https:\/\/moh.gov.so\/en\/wp-content\/uploads\/2022\/07\/271707230_295945135892800_6969106877740325906_n.jpg","width":515,"height":515,"caption":"Ministry Of Health & Human Services- Federal Government Of Somalia (FGS)"},"image":{"@id":"https:\/\/moh.gov.so\/so\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MoHSomalia","https:\/\/x.com\/MoH_Somalia","https:\/\/www.youtube.com\/c\/MinistryofHealthSomalia","https:\/\/moh.gov.so\/en"]}]}},"_links":{"self":[{"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/pages\/12404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/comments?post=12404"}],"version-history":[{"count":18,"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/pages\/12404\/revisions"}],"predecessor-version":[{"id":12634,"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/pages\/12404\/revisions\/12634"}],"wp:attachment":[{"href":"https:\/\/moh.gov.so\/so\/wp-json\/wp\/v2\/media?parent=12404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}